{"id":4842,"date":"2016-09-06T10:47:37","date_gmt":"2016-09-06T09:47:37","guid":{"rendered":"http:\/\/www.legalprofession.de\/?p=4842"},"modified":"2023-06-29T13:54:38","modified_gmt":"2023-06-29T11:54:38","slug":"anwaltszukunftskongress-2016","status":"publish","type":"post","link":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016","title":{"rendered":"Anwaltszukunftskongress 2016"},"content":{"rendered":"<h4>Erster Anwaltszukunftskongress September 2016 in K\u00f6ln<\/h4>\n<h4 style=\"text-align: justify;\"><span style=\"color: #dd2550;\">Anw\u00e4lte blicken nicht mehr nur \u00fcber den Tellerrand, sondern auch in die Zukunft.<\/span><\/h4>\n<p style=\"text-align: justify;\">Der Blick in die Zukunft ist einigen Berufsgruppen schon aufgrund ihrer Profession\u00a0nicht gegeben, umso erfreulicher, dass nun auch die deutschen Rechtsanw\u00e4lte nicht nur \u00fcber den eigenen Tellerrand, sondern gemeinsam in die Zukunft blicken, wenn auch oft begleitet von einem leichten Kopfsch\u00fctteln. Verst\u00e4ndlich, denn\u00a0dieser Ansto\u00df zur gemeinsamen Zukunftsschau kam (noch)\u00a0nicht aus der eigenen anwaltlichen Selbstverwaltung, daf\u00fcr haben zwei der gro\u00dfen Servicedienstleister der Anwaltschaft die Sache beherzt in ihre professionellen H\u00e4nde genommen. Die <a href=\"https:\/\/www.wolterskluwer.de\/\">Wolters Kluwer Deutschland GmbH <\/a>&#8211; einer der f\u00fchrenden Wissens- und Informationsdienstleister in den Bereichen Recht, Wirtschaft und Steuern &#8211; und die <a href=\"https:\/\/www.soldan.de\/\">Hans Soldan GmbH<\/a> &#8211; der f\u00fchrende Anbieter f\u00fcr Kanzleibedarf, Fachmedien und B\u00fcrodienstleistungen f\u00fcr Anw\u00e4lte, Notare, Steuerberater und Wirtschaftspr\u00fcfer in Deutschland &#8211; haben gemeinsam am 2. und 3. September den 1. Anwaltszukunftskongress in K\u00f6ln ausgerichtet.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #dd2550;\">Der Anwaltszukunftskongress- ein gelungener Event<\/span><\/h4>\n<p style=\"text-align: justify;\">Um es an dieser Stelle vorweg zu nehmen, es war ein gelungener Event, der in \u00a0jedem Fall fortgef\u00fchrt werden sollte. Ob es dann, wie fast alles in unserer Zeit, noch einmal gr\u00f6\u00dfer, besser und schneller werden sollte? Eher nicht. Die Gr\u00f6\u00dfe, mit 360 Teilnehmern in dem gut gef\u00fcllten und eng bestuhlten Kongresszentrum des Hotels Marriott in K\u00f6ln, bot gerade noch Gelegenheit zu einem pers\u00f6nlichen Kennenlernen und Gedankenaustausch bei Kaffee, Snack oder Lunch. Besser machen kann man solch eine Veranstaltung\u00a0kaum, es war informativ, aufr\u00fcttelnd und unterhaltsam, was schon die Auswahl der Referenten auf der <a href=\"http:\/\/www.anwaltszukunftskongress.de\/agenda\/?gclid=Cj0KEQjw0rm-BRCn85bm8uS-zK0BEiQAHo4vrHrz8OuX4F2Ax40ZHKU63nb8iacdHYh7p-7vlbUjXu8aAtgy8P8HAQ\">Agenda<\/a> versprach. Vom Justizminister von NRW, Thomas Kutschaty, \u00fcber Prof. Dr. Roland Vogel der Stanford Law School \u00a0und \u00a0dem Mathematikprofessor Dr. Gunter Dueck, der als lockerer Business Engel aufmunterte, bis zu Extremsportler und Berufsmotivator Joey Kelly, um nur einige der Hochkar\u00e4ter zu nennen, gab es eine bunte Palette von Ein- und Ausblicken in Visionen und Zukunftsthemen, die man anderenorts sogar schon gestaltet hat. Die Teilnehmer waren neugierig, interessiert und begeisterungsf\u00e4hig. Ein sch\u00f6nes Bild f\u00fcr die Anwaltschaft, dies w\u00fcnscht man sich \u00f6fter. Schneller sollte es auch nicht werden, die beiden Tage waren gut gef\u00fcllt, wie auch der Kopf. Insofern hat der abendliche Cocktail dann auch endlich die Gedanken zwischen Legal-Tech und Zukunftsangst etwas ruhen oder bei manchem auch kreisen lassen.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #dd2550;\">Die Zukunft bringt nichts &#8211; wir m\u00fcssen sie gestalten<\/span><\/h4>\n<p style=\"text-align: justify;\">Aber der Blick in die Zukunft ist ja bekanntlich auch nicht ohne Risiko. Schlie\u00dflich kann es passieren, dass man pl\u00f6tzlich erkennt, dass das, was man in der Ferne zu sehen glaubt, gar nicht die Zukunft ist, sondern die Gegenwart. Es kann sein, dass man aufwacht und merkt, dass man an altem, l\u00e4ngst Vergangenem festh\u00e4lt und l\u00e4ngst\u00a0eher in der Vergangenheit als in der Gegenwart lebt. Und es ist nicht nur die Technik, die sich gravierend ver\u00e4ndert hat. Wenn auch die Pr\u00e4sentationen der neuen Versionen der Kanzleisoftware- und Cloudl\u00f6sungen, der Sprach- und Stimmerkennung und der Legal-Tech-Portale\u00a0am Rande des Kongresses beeindruckend waren, das ist nur Technik, das kann man alles lernen und beherrschen. Was aber wirklich besorgniserregend ist, ist die Feststellung, dass sich offensichtlich auch die Menschen ver\u00e4ndert haben. Wenn Recruiting auch nur eine Nebenrolle auf dem Anwaltszukunftskongress spielte, hier war die Unsicherheit, was uns da noch bevor steht oder wer in Zukunft vor unserer T\u00fcr steht, am deutlichsten zu sp\u00fcren. Die Generation Y gibt es wirklich, so die Feststellung der ntv &#8211; Moderatorin Rommy Arndt, die charmant durch den Kongress f\u00fchrte. Auch wenn diese Generation Y schon zu Z mutiert, sie diktiert die Zukunft. Da w\u00fcrde sich so manche Kanzlei wohl eher mit <a href=\"http:\/\/www.ibm.com\/watson\/what-is-watson.html?mkwid=&amp;cm_mmc=&amp;cm_mmca2=\">\u201eWatson\u201c<\/a> anfreunden, als mit einem unangepassten Nachwuchskandidaten. Insofern hat k\u00fcnstliche Intelligenz auch einen Vorteil: Man kann sie f\u00fcttern und die frisst einem aus der Hand. Noch jedenfalls.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #dd2550;\">Zukunft beginnt mit Gedankenaustausch<\/span><\/h4>\n<p style=\"text-align: justify;\">Bei allem Unmut \u00fcber die junge Generation, mit ihrem Anspruch an Sinnhaftigkeit nebst\u00a0Selbstbestimmung mit Freizeitausgleich, d\u00fcrfen wir nicht \u00fcbersehen, dass sie die Zukunft gestalten wird, w\u00e4hrend wir oft noch warten, dass die Zukunft\u00a0kommt und auch noch etwas bringt. Dass die Jugend\u00a0damit bereits begonnen hat, zeigten die Legal-Tech Gr\u00fcnder auf dem Anwaltszukunftskongress in K\u00f6ln auf lockere\u00a0Weise. Die Veranstaltung war ein wichtiger Schritt zu einem gemeinsamen Diskurs zwischen Anwaltszunft, Technikfreak und IT-Nerd, zwischen jungen und erfahren Menschen, zwischen Plattformberatung\u00a0und Berufsrecht. Hier gibt es noch viel zu diskutieren &#8211; nicht erst in der Zukunft. Die n\u00e4chste Gelegenheit bietet\u00a0der <a href=\"http:\/\/anwaltstag.de\/de\/ueber-den-anwaltstag\">Deutsche Anwaltstag 2017<\/a> in Essen zum Thema Digitalisierung.<\/p>\n<p style=\"text-align: justify;\">LTO-Sonderver\u00f6ffentlichung- <a href=\"http:\/\/www.lto.de\/fileadmin\/files\/statische_seiten\/presse\/Die_neuen_Juristen_Webzine.pdf\">Die neuen Juristen <\/a>&#8211; zum Download<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erster Anwaltszukunftskongress September 2016 in K\u00f6ln Anw\u00e4lte blicken nicht mehr nur \u00fcber den Tellerrand, sondern auch in die Zukunft. Der Blick in die Zukunft ist einigen Berufsgruppen schon aufgrund ihrer Profession\u00a0nicht gegeben, umso erfreulicher, dass nun auch die deutschen Rechtsanw\u00e4lte nicht nur \u00fcber den eigenen Tellerrand, sondern gemeinsam in die Zukunft blicken, wenn auch oft&hellip; <a href=\"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016\">Continue reading&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":8835,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[124,317,1],"tags":[318,119,351,347],"class_list":["post-4842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbeitgeber","category-kanzleiorganisation","category-universum","tag-digitalisierung","tag-kanzleimanagement","tag-kanzleisoftware","tag-legal-tech"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anwaltszukunftskongress 2016 - LegalProfession\u00ae<\/title>\n<meta name=\"description\" content=\"Erster Anwaltszukunftskongress September 2016 in K\u00f6ln. Anw\u00e4lte blicken nicht mehr nur \u00fcber den Tellerrand, sondern auch in die Zukunft.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anwaltszukunftskongress 2016 - LegalProfession\u00ae\" \/>\n<meta property=\"og:description\" content=\"Erster Anwaltszukunftskongress September 2016 in K\u00f6ln. Anw\u00e4lte blicken nicht mehr nur \u00fcber den Tellerrand, sondern auch in die Zukunft.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016\" \/>\n<meta property=\"og:site_name\" content=\"LegalProfession\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-06T09:47:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-29T11:54:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.legalprofession.de\/wp-content\/uploads\/IMG_3309-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1989\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marion Proft\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marion Proft\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016\"},\"author\":{\"name\":\"Marion Proft\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/person\\\/1e8822e456f8b1f7b7a81e32b14f81cf\"},\"headline\":\"Anwaltszukunftskongress 2016\",\"datePublished\":\"2016-09-06T09:47:37+00:00\",\"dateModified\":\"2023-06-29T11:54:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016\"},\"wordCount\":772,\"publisher\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/IMG_3309-scaled.jpg?fit=2560%2C1989&ssl=1\",\"keywords\":[\"Digitalisierung\",\"Kanzleimanagement\",\"Kanzleisoftware\",\"Legal Tech\"],\"articleSection\":[\"Arbeitgeber\",\"Kanzleiorganisation\",\"Universum\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016\",\"name\":\"Anwaltszukunftskongress 2016 - LegalProfession\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/IMG_3309-scaled.jpg?fit=2560%2C1989&ssl=1\",\"datePublished\":\"2016-09-06T09:47:37+00:00\",\"dateModified\":\"2023-06-29T11:54:38+00:00\",\"description\":\"Erster Anwaltszukunftskongress September 2016 in K\u00f6ln. Anw\u00e4lte blicken nicht mehr nur \u00fcber den Tellerrand, sondern auch in die Zukunft.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/IMG_3309-scaled.jpg?fit=2560%2C1989&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/IMG_3309-scaled.jpg?fit=2560%2C1989&ssl=1\",\"width\":2560,\"height\":1989,\"caption\":\"Erster Anwaltszukunftskongress 2016 K\u00f6ln\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/anwaltszukunftskongress-2016#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.legalprofession.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anwaltszukunftskongress 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#website\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/\",\"name\":\"LegalProfession\u00ae\",\"description\":\"Recruiting Coaching Consulting AZAV\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.legalprofession.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\",\"name\":\"LegalProfession\u00ae Recruitment Coaching Consulting\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Logo-LP-1.jpg?fit=354%2C141&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Logo-LP-1.jpg?fit=354%2C141&ssl=1\",\"width\":354,\"height\":141,\"caption\":\"LegalProfession\u00ae Recruitment Coaching Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/marion-proft-legalprofession\\\/\",\"https:\\\/\\\/www.xing.com\\\/profile\\\/Marion_Proft\\\/portfolio\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/person\\\/1e8822e456f8b1f7b7a81e32b14f81cf\",\"name\":\"Marion Proft\",\"description\":\"Marion Proft Recruitment, Coaching &amp; Berufsorientierung - AZAV Arbeitsvermittlung &amp; Job Coaching. Pers\u00f6nlich-professionell-perspektivisch. Zuversicht &amp; Future Fitness in unsicheren Zeiten.\",\"sameAs\":[\"https:\\\/\\\/www.legalprofession.de\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/marion-proft-legalprofession\\\/\"],\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/author\\\/admin-mpr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anwaltszukunftskongress 2016 - LegalProfession\u00ae","description":"Erster Anwaltszukunftskongress September 2016 in K\u00f6ln. Anw\u00e4lte blicken nicht mehr nur \u00fcber den Tellerrand, sondern auch in die Zukunft.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016","og_locale":"de_DE","og_type":"article","og_title":"Anwaltszukunftskongress 2016 - LegalProfession\u00ae","og_description":"Erster Anwaltszukunftskongress September 2016 in K\u00f6ln. Anw\u00e4lte blicken nicht mehr nur \u00fcber den Tellerrand, sondern auch in die Zukunft.","og_url":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016","og_site_name":"LegalProfession\u00ae","article_published_time":"2016-09-06T09:47:37+00:00","article_modified_time":"2023-06-29T11:54:38+00:00","og_image":[{"width":2560,"height":1989,"url":"https:\/\/www.legalprofession.de\/wp-content\/uploads\/IMG_3309-scaled.jpg","type":"image\/jpeg"}],"author":"Marion Proft","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Marion Proft","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016#article","isPartOf":{"@id":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016"},"author":{"name":"Marion Proft","@id":"https:\/\/www.legalprofession.de\/#\/schema\/person\/1e8822e456f8b1f7b7a81e32b14f81cf"},"headline":"Anwaltszukunftskongress 2016","datePublished":"2016-09-06T09:47:37+00:00","dateModified":"2023-06-29T11:54:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016"},"wordCount":772,"publisher":{"@id":"https:\/\/www.legalprofession.de\/#organization"},"image":{"@id":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/IMG_3309-scaled.jpg?fit=2560%2C1989&ssl=1","keywords":["Digitalisierung","Kanzleimanagement","Kanzleisoftware","Legal Tech"],"articleSection":["Arbeitgeber","Kanzleiorganisation","Universum"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016","url":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016","name":"Anwaltszukunftskongress 2016 - LegalProfession\u00ae","isPartOf":{"@id":"https:\/\/www.legalprofession.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016#primaryimage"},"image":{"@id":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/IMG_3309-scaled.jpg?fit=2560%2C1989&ssl=1","datePublished":"2016-09-06T09:47:37+00:00","dateModified":"2023-06-29T11:54:38+00:00","description":"Erster Anwaltszukunftskongress September 2016 in K\u00f6ln. Anw\u00e4lte blicken nicht mehr nur \u00fcber den Tellerrand, sondern auch in die Zukunft.","breadcrumb":{"@id":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016#primaryimage","url":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/IMG_3309-scaled.jpg?fit=2560%2C1989&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/IMG_3309-scaled.jpg?fit=2560%2C1989&ssl=1","width":2560,"height":1989,"caption":"Erster Anwaltszukunftskongress 2016 K\u00f6ln"},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalprofession.de\/index.php\/anwaltszukunftskongress-2016#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.legalprofession.de\/"},{"@type":"ListItem","position":2,"name":"Anwaltszukunftskongress 2016"}]},{"@type":"WebSite","@id":"https:\/\/www.legalprofession.de\/#website","url":"https:\/\/www.legalprofession.de\/","name":"LegalProfession\u00ae","description":"Recruiting Coaching Consulting AZAV","publisher":{"@id":"https:\/\/www.legalprofession.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalprofession.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.legalprofession.de\/#organization","name":"LegalProfession\u00ae Recruitment Coaching Consulting","url":"https:\/\/www.legalprofession.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalprofession.de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Logo-LP-1.jpg?fit=354%2C141&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Logo-LP-1.jpg?fit=354%2C141&ssl=1","width":354,"height":141,"caption":"LegalProfession\u00ae Recruitment Coaching Consulting"},"image":{"@id":"https:\/\/www.legalprofession.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/in\/marion-proft-legalprofession\/","https:\/\/www.xing.com\/profile\/Marion_Proft\/portfolio"]},{"@type":"Person","@id":"https:\/\/www.legalprofession.de\/#\/schema\/person\/1e8822e456f8b1f7b7a81e32b14f81cf","name":"Marion Proft","description":"Marion Proft Recruitment, Coaching &amp; Berufsorientierung - AZAV Arbeitsvermittlung &amp; Job Coaching. Pers\u00f6nlich-professionell-perspektivisch. Zuversicht &amp; Future Fitness in unsicheren Zeiten.","sameAs":["https:\/\/www.legalprofession.de","https:\/\/www.linkedin.com\/in\/marion-proft-legalprofession\/"],"url":"https:\/\/www.legalprofession.de\/index.php\/author\/admin-mpr"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/IMG_3309-scaled.jpg?fit=2560%2C1989&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8oDIe-1g6","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts\/4842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/comments?post=4842"}],"version-history":[{"count":0,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts\/4842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/media\/8835"}],"wp:attachment":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/media?parent=4842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/categories?post=4842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/tags?post=4842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}