{"id":4942,"date":"2016-10-05T22:10:21","date_gmt":"2016-10-05T21:10:21","guid":{"rendered":"http:\/\/www.legalprofession.de\/?p=4942"},"modified":"2020-03-14T23:28:42","modified_gmt":"2020-03-14T22:28:42","slug":"her-mit-deinen-daten","status":"publish","type":"post","link":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten","title":{"rendered":"Her mit deinen Daten &#8211; ich garantiere f\u00fcr nichts!"},"content":{"rendered":"<p style=\"text-align: justify;\">Daniel hat seinen Master of Laws fast in der Tasche, er ist in der\u00a0Bewerbungsphase. Stolz auf seine Abschl\u00fcsse (Kaufmann, LL.B und LL.M) und seine ersten beruflichen Erfahrungen, f\u00fcllt er sein xing-Profil\u00a0aus: Vertragsmanagement, Kaufrecht, HR, Arbeitsrecht, Compliance. Bisher sucht er ja mehr, als er zu bieten hat, aber als Berufseinsteiger ist er ungebunden, flexibel und offen f\u00fcr Neues.\u00a0Zwei Tage sp\u00e4ter meldet sich Mandy:<\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"4943\" data-permalink=\"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten\/xing\" data-orig-file=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Xing.jpg?fit=650%2C336&amp;ssl=1\" data-orig-size=\"650,336\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"xing\" data-image-description=\"&lt;p&gt;xing Ansprache&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Xing.jpg?fit=650%2C336&amp;ssl=1\" class=\"wp-image-4943 size-medium alignnone\" src=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Xing.jpg?resize=300%2C155&#038;ssl=1\" alt=\"xing\" width=\"300\" height=\"155\" srcset=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Xing.jpg?resize=300%2C155&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Xing.jpg?resize=600%2C310&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Xing.jpg?w=650&amp;ssl=1 650w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\">Der Angesprochene schaut auf Mandys xing-Profil: Sie arbeitet bei einem Personaldienstleister in Hamburg, es scheint ihr\u00a0erster Job zu sein. Ihre Ausbildung: Universit\u00e4t \u00a0Hamburg, keine Jahreszahl, keine Fachrichtung, offensichtlich ohne Abschluss. Neben ihrem Foto mit dem etwas fragenden Blick steht: \u201eInternational Recruiter &amp; Business Development\u201d. Daniel sucht\u00a0nach der Firma, Mandy ist auf der Homepage\u00a0nicht zu finden. Aber die Branche klingt spannend: Luftfahrt. Er sucht unter den Job Opportunities nach der Vakanz. Es m\u00fcsste ja etwas mit Jura sein, wenn das f\u00fcr einen Wirtschaftsjuristen passen sollte. Er findet eine Juristenstelle im Vertragsmanagement: 3 Jahre Berufserfahrung, Vollzeit ab sofort (A\u00dcG), in Hamburg. Daniel sendet seinen CV mit dem Hinweis, dass er in Berlin wohnt. Kurz darauf klingelt sein Handy.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #dd2556;\">Der Recruiter\u00a0ruft an<\/span><\/h4>\n<p style=\"text-align: justify;\">Mandy ist begeistert, dass er alles schon gemacht hat, was die Stelle fordert. Daniel verweist vorsichtshalber darauf, dass seine Erfahrungen, die er studienbegleitend\u00a0 erworben hat, wohl noch nicht ganz dem Umfang und den Anforderungen ihres Kunden in der Luftfahrtindustrie entsprechen k\u00f6nnten. Er stellt einige konkrete Fragen zu den Aufgaben und dem Verantwortungsbereich der Position, die sie leider nicht beantworten kann. Mandy meint, es steht doch alles in der Stellenbeschreibung, die er \u00fcbrigens gut recherchiert hat, sie kichert. Dann wieder ernst <em>\u201cIch brauche jetzt \u00a0erst einmal weitere Unterlagen von Ihnen und nat\u00fcrlich Ihren Gehaltswunsch.\u201d<\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Der Einstellungsfragebogen l\u00e4sst keine Fragen offen. Von der Einwilligung zu Milit\u00e4rprojekten bis zur Schwerbehinderung und der l\u00fcckenlosen Aufz\u00e4hlung aller bisherigen Arbeitgeber sowie\u00a0der dort erworbenen Fachkenntnisse wird\u00a0auf 5 Formularseiten alles abgefragt.\u00a0Was passiert eigentlich mit den\u00a0Daten nach dem Auswahlprozess? Daniel fragt nach einer Datenschutzerkl\u00e4rung, Mandy reagiert verschnupft.<\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"4948\" data-permalink=\"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten\/mail-3\" data-orig-file=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-3.jpg?fit=1292%2C128&amp;ssl=1\" data-orig-size=\"1292,128\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"mail-3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-3.jpg?fit=770%2C76&amp;ssl=1\" class=\"wp-image-4948 size-large alignleft\" src=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-3.jpg?resize=770%2C76&#038;ssl=1\" alt=\"mail-3\" width=\"770\" height=\"76\" srcset=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-3.jpg?resize=1024%2C101&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-3.jpg?resize=300%2C30&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-3.jpg?resize=600%2C59&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-3.jpg?resize=1170%2C116&amp;ssl=1 1170w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-3.jpg?w=1292&amp;ssl=1 1292w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p style=\"text-align: justify;\">Daniel sendet ihr den Link zu der Datenschutzerkl\u00e4rung auf ihrer Homepage und den ausgef\u00fcllten Fragebogen. Sie will noch mehr.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"4952\" data-permalink=\"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten\/mail-2\" data-orig-file=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-2.jpg?fit=1756%2C601&amp;ssl=1\" data-orig-size=\"1756,601\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"mail-2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-2.jpg?fit=770%2C263&amp;ssl=1\" class=\"wp-image-4952 size-large alignnone\" src=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-2.jpg?resize=770%2C263&#038;ssl=1\" alt=\"mail-2\" width=\"770\" height=\"263\" srcset=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-2.jpg?resize=1024%2C350&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-2.jpg?resize=300%2C103&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-2.jpg?resize=600%2C205&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-2.jpg?resize=1170%2C400&amp;ssl=1 1170w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-2.jpg?w=1756&amp;ssl=1 1756w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-2.jpg?w=1540&amp;ssl=1 1540w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #dd2556;\">Daniel f\u00e4hrt zum Vorstellungsgespr\u00e4ch nach\u00a0Hamburg &#8211; auf eigene Kosten<\/span><\/h4>\n<p style=\"text-align: justify;\">Mandy hat leider keine Zeit, ihn pers\u00f6nlich kennen zu lernen. Aber ihr Kunde, der Leiter Vertragsmanagement, empf\u00e4ngt Daniel\u00a0freundlich und nimmt sich \u00fcber eine Stunde Zeit f\u00fcr ein offenes Gespr\u00e4ch auf dem Firmengel\u00e4nde. Nach den ersten Minuten steht fest, dass die ausgeschriebene Stellenanzeige nichts mit der tats\u00e4chlichen Vakanz in dem Luftfahrtunternehmen zu tun hat. Der Kunde sucht eine Krankheitsvertretung in Teilzeit, maximal 30 Stunden, mit \u00fcberwiegend administrativen Aufgaben und nur einem juristischen Schwerpunkt, Pr\u00fcfung von Handelsvertretervertr\u00e4gen, maximal f\u00fcr 6 Monate, ohne Option der Verl\u00e4ngerung &#8211; Arbeitsbeginn am kommenden Montag. Er fragt Daniel, warum er sich als Berliner denn auf diese Position beworben hat und ob er nicht selbst denkt, dass er als Wirtschaftsjurist \u00fcberqualifiziert w\u00e4re?<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #dd2556;\">Auf der R\u00fcckfahrt nach Berlin ruft Mandy an\u00a0<\/span><\/h4>\n<p style=\"text-align: justify;\"><em>&#8222;&#8230;und wie hat es Ihnen gefallen, machen Sie den Job?&#8220;<\/em> Daniel fragt sich, ob sie denn schon mit dem\u00a0Kunden gesprochen\u00a0hat. Er atmet tief durch, in ihm brodelt es. <em>&#8222;Da gibt es keinen Job, den ich annehmen k\u00f6nnte. Ihr Kunde hat mir geschildert, was er eigentlich sucht und vor allem zu\u00a0welchen Konditionen.&#8220;<\/em> Mandy etwas aufgebracht: <em>&#8222;Wie, hat er jetzt alles widerrufen? Das ist die Schuld des Kunden, mir hat er was ganz anderes erz\u00e4hlt. W\u00e4re es aber trotzdem f\u00fcr Sie interessant?&#8220;<\/em><\/p>\n<p style=\"text-align: justify;\">Jetzt reagiert\u00a0auch er energisch: <em>&#8222;Noch einmal, selbst wenn ich die Aufgabe annehmen w\u00fcrde, weil mich ehrlich gesagt die Branche und das Unternehmen reizt, auch k\u00f6nnte ich mir\u00a0Ihren Kunden als Chef gut vorstellen &#8212; ich kann nicht in der n\u00e4chsten Woche an Hamburg anfangen, ich wohne in Berlin. Nur falls Sie es immer noch nicht geschnallt haben, ich kann weder unter der Br\u00fccke noch im Auto schlafen, ich brauche zumindest eine Bleibe in Hamburg.&#8220;<\/em><\/p>\n<p style=\"text-align: justify;\"><em>&#8222;Na, ich habe ja ganz viel Connection in Hamburg, da k\u00f6nnen wir doch was machen, sagen Sie mal eine Zahl.&#8220;<\/em> Daniel stutz: <em>&#8222;Was f\u00fcr eine Zahl?&#8220;<\/em><\/p>\n<p style=\"text-align: justify;\"><em>&#8222;Was Sie verdienen m\u00fcssen, damit Sie sich hier eine Wohnung mieten k\u00f6nnen. Aber vorher brauche ich noch die G37 Untersuchung, die haben Sie immer noch nicht gemacht.&#8220;<\/em> Daniel neigt sich ganz weit nach vorn und umklammert das Lenkrad, als wollte er vor Wut hineinbei\u00dfen. Er spricht langsam und ganz leise, wie zu einem kranken Haustier: <em>&#8222;Liebe Mandy, die G37 ist eine freiwillige Untersuchung nach der Bildschirmarbeitsplatzverordnung, die der Arbeitgeber dem Mitarbeiter anbieten muss und der Arbeitnehmer in Anspruch nehmen kann. Zur Erinnerung, ich bin Jurist. Ich werde nicht noch 100 Euro daf\u00fcr bezahlen, damit Sie Ihre Datenbank mit meinen Unterlagen f\u00fcllen k\u00f6nnen. Und \u00fcberhaupt, was sagt eigentlich Ihr Kunde, gab es schon ein Feedback?<\/em><\/p>\n<p style=\"text-align: justify;\"><em>&#8222;Nein, aber wenn das mit der Stelle nicht klappt, ich habe ja immer wieder mal was f\u00fcr Juristen in Hamburg.&#8220;<\/em><\/p>\n<p style=\"text-align: justify;\">Am n\u00e4chsten Tag kam die Absage\u00a0per Mail.<\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4974\" data-permalink=\"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten\/mail-4a\" data-orig-file=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-4a.jpg?fit=954%2C457&amp;ssl=1\" data-orig-size=\"954,457\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"mail-4a\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-4a.jpg?fit=770%2C369&amp;ssl=1\" class=\"alignnone wp-image-4974\" src=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-4a.jpg?resize=600%2C287&#038;ssl=1\" alt=\"mail-4a\" width=\"600\" height=\"287\" srcset=\"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-4a.jpg?resize=300%2C144&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-4a.jpg?resize=600%2C287&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Mail-4a.jpg?w=954&amp;ssl=1 954w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: justify;\">Daniel hat das Angebot zur\u00a0Datenl\u00f6schung angenommen. Die Reisekosten tr\u00e4gt er selbst, immer noch besser, als dort arbeiten zu m\u00fcssen. Er hat sich per Mail\u00a0direkt beim\u00a0Kunden bedankt,\u00a0f\u00fcr die offenen Worte und seine\u00a0Zeit, ihn auf dem Firmengel\u00e4nde zu empfangen. Nebenbei hat er empfohlen, sich nach einem f\u00e4higen\u00a0Personaldienstleister umzuschauen, denn ansonsten h\u00e4tte er Angst, in ein Flugzeug zu steigen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daniel hat seinen Master of Laws fast in der Tasche, er ist in der\u00a0Bewerbungsphase. Stolz auf seine Abschl\u00fcsse (Kaufmann, LL.B und LL.M) und seine ersten beruflichen Erfahrungen, f\u00fcllt er sein xing-Profil\u00a0aus: Vertragsmanagement, Kaufrecht, HR, Arbeitsrecht, Compliance. Bisher sucht er ja mehr, als er zu bieten hat, aber als Berufseinsteiger ist er ungebunden, flexibel und offen&hellip; <a href=\"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten\">Continue reading&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[291,265,241],"tags":[32,365],"class_list":["post-4942","post","type-post","status-publish","format-standard","hentry","category-bewerber","category-recruitment","category-wirtschaftsjuristen","tag-headhunter","tag-personaldienstleister"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Her mit deinen Daten - ich garantiere f\u00fcr nichts! - LegalProfession\u00ae<\/title>\n<meta name=\"description\" content=\"Daniel hat seinen Master of Laws fast in der Tasche, er ist in der\u00a0Bewerbungsphase. Stolz auf seine Abschl\u00fcsse, f\u00fcllt er sein xing-Profil\u00a0aus:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Her mit deinen Daten - ich garantiere f\u00fcr nichts! - LegalProfession\u00ae\" \/>\n<meta property=\"og:description\" content=\"Daniel hat seinen Master of Laws fast in der Tasche, er ist in der\u00a0Bewerbungsphase. Stolz auf seine Abschl\u00fcsse, f\u00fcllt er sein xing-Profil\u00a0aus:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten\" \/>\n<meta property=\"og:site_name\" content=\"LegalProfession\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-05T21:10:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-14T22:28:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.legalprofession.de\/wp-content\/uploads\/Xing-300x155.jpg\" \/>\n<meta name=\"author\" content=\"Marion Proft\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marion Proft\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten\"},\"author\":{\"name\":\"Marion Proft\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/person\\\/1e8822e456f8b1f7b7a81e32b14f81cf\"},\"headline\":\"Her mit deinen Daten &#8211; ich garantiere f\u00fcr nichts!\",\"datePublished\":\"2016-10-05T21:10:21+00:00\",\"dateModified\":\"2020-03-14T22:28:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten\"},\"wordCount\":934,\"publisher\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Xing-300x155.jpg\",\"keywords\":[\"Headhunter\",\"Personaldienstleister\"],\"articleSection\":[\"Bewerber\",\"Recruitment\",\"Wirtschaftsjuristen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten\",\"name\":\"Her mit deinen Daten - ich garantiere f\u00fcr nichts! - LegalProfession\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Xing-300x155.jpg\",\"datePublished\":\"2016-10-05T21:10:21+00:00\",\"dateModified\":\"2020-03-14T22:28:42+00:00\",\"description\":\"Daniel hat seinen Master of Laws fast in der Tasche, er ist in der\u00a0Bewerbungsphase. Stolz auf seine Abschl\u00fcsse, f\u00fcllt er sein xing-Profil\u00a0aus:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten#primaryimage\",\"url\":\"http:\\\/\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Xing-300x155.jpg\",\"contentUrl\":\"http:\\\/\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Xing-300x155.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/her-mit-deinen-daten#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.legalprofession.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Her mit deinen Daten &#8211; ich garantiere f\u00fcr nichts!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#website\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/\",\"name\":\"LegalProfession\u00ae\",\"description\":\"Recruiting Coaching Consulting AZAV\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.legalprofession.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\",\"name\":\"LegalProfession\u00ae Recruitment Coaching Consulting\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Logo-LP-1.jpg?fit=354%2C141&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Logo-LP-1.jpg?fit=354%2C141&ssl=1\",\"width\":354,\"height\":141,\"caption\":\"LegalProfession\u00ae Recruitment Coaching Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/marion-proft-legalprofession\\\/\",\"https:\\\/\\\/www.xing.com\\\/profile\\\/Marion_Proft\\\/portfolio\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/person\\\/1e8822e456f8b1f7b7a81e32b14f81cf\",\"name\":\"Marion Proft\",\"description\":\"Marion Proft Recruitment, Coaching &amp; Berufsorientierung - AZAV Arbeitsvermittlung &amp; Job Coaching. Pers\u00f6nlich-professionell-perspektivisch. Zuversicht &amp; Future Fitness in unsicheren Zeiten.\",\"sameAs\":[\"https:\\\/\\\/www.legalprofession.de\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/marion-proft-legalprofession\\\/\"],\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/author\\\/admin-mpr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Her mit deinen Daten - ich garantiere f\u00fcr nichts! - LegalProfession\u00ae","description":"Daniel hat seinen Master of Laws fast in der Tasche, er ist in der\u00a0Bewerbungsphase. Stolz auf seine Abschl\u00fcsse, f\u00fcllt er sein xing-Profil\u00a0aus:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten","og_locale":"de_DE","og_type":"article","og_title":"Her mit deinen Daten - ich garantiere f\u00fcr nichts! - LegalProfession\u00ae","og_description":"Daniel hat seinen Master of Laws fast in der Tasche, er ist in der\u00a0Bewerbungsphase. Stolz auf seine Abschl\u00fcsse, f\u00fcllt er sein xing-Profil\u00a0aus:","og_url":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten","og_site_name":"LegalProfession\u00ae","article_published_time":"2016-10-05T21:10:21+00:00","article_modified_time":"2020-03-14T22:28:42+00:00","og_image":[{"url":"http:\/\/www.legalprofession.de\/wp-content\/uploads\/Xing-300x155.jpg","type":"","width":"","height":""}],"author":"Marion Proft","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Marion Proft","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten#article","isPartOf":{"@id":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten"},"author":{"name":"Marion Proft","@id":"https:\/\/www.legalprofession.de\/#\/schema\/person\/1e8822e456f8b1f7b7a81e32b14f81cf"},"headline":"Her mit deinen Daten &#8211; ich garantiere f\u00fcr nichts!","datePublished":"2016-10-05T21:10:21+00:00","dateModified":"2020-03-14T22:28:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten"},"wordCount":934,"publisher":{"@id":"https:\/\/www.legalprofession.de\/#organization"},"image":{"@id":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten#primaryimage"},"thumbnailUrl":"http:\/\/www.legalprofession.de\/wp-content\/uploads\/Xing-300x155.jpg","keywords":["Headhunter","Personaldienstleister"],"articleSection":["Bewerber","Recruitment","Wirtschaftsjuristen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten","url":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten","name":"Her mit deinen Daten - ich garantiere f\u00fcr nichts! - LegalProfession\u00ae","isPartOf":{"@id":"https:\/\/www.legalprofession.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten#primaryimage"},"image":{"@id":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten#primaryimage"},"thumbnailUrl":"http:\/\/www.legalprofession.de\/wp-content\/uploads\/Xing-300x155.jpg","datePublished":"2016-10-05T21:10:21+00:00","dateModified":"2020-03-14T22:28:42+00:00","description":"Daniel hat seinen Master of Laws fast in der Tasche, er ist in der\u00a0Bewerbungsphase. Stolz auf seine Abschl\u00fcsse, f\u00fcllt er sein xing-Profil\u00a0aus:","breadcrumb":{"@id":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten#primaryimage","url":"http:\/\/www.legalprofession.de\/wp-content\/uploads\/Xing-300x155.jpg","contentUrl":"http:\/\/www.legalprofession.de\/wp-content\/uploads\/Xing-300x155.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalprofession.de\/index.php\/her-mit-deinen-daten#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.legalprofession.de\/"},{"@type":"ListItem","position":2,"name":"Her mit deinen Daten &#8211; ich garantiere f\u00fcr nichts!"}]},{"@type":"WebSite","@id":"https:\/\/www.legalprofession.de\/#website","url":"https:\/\/www.legalprofession.de\/","name":"LegalProfession\u00ae","description":"Recruiting Coaching Consulting AZAV","publisher":{"@id":"https:\/\/www.legalprofession.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalprofession.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.legalprofession.de\/#organization","name":"LegalProfession\u00ae Recruitment Coaching Consulting","url":"https:\/\/www.legalprofession.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalprofession.de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Logo-LP-1.jpg?fit=354%2C141&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Logo-LP-1.jpg?fit=354%2C141&ssl=1","width":354,"height":141,"caption":"LegalProfession\u00ae Recruitment Coaching Consulting"},"image":{"@id":"https:\/\/www.legalprofession.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/in\/marion-proft-legalprofession\/","https:\/\/www.xing.com\/profile\/Marion_Proft\/portfolio"]},{"@type":"Person","@id":"https:\/\/www.legalprofession.de\/#\/schema\/person\/1e8822e456f8b1f7b7a81e32b14f81cf","name":"Marion Proft","description":"Marion Proft Recruitment, Coaching &amp; Berufsorientierung - AZAV Arbeitsvermittlung &amp; Job Coaching. Pers\u00f6nlich-professionell-perspektivisch. Zuversicht &amp; Future Fitness in unsicheren Zeiten.","sameAs":["https:\/\/www.legalprofession.de","https:\/\/www.linkedin.com\/in\/marion-proft-legalprofession\/"],"url":"https:\/\/www.legalprofession.de\/index.php\/author\/admin-mpr"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p8oDIe-1hI","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts\/4942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/comments?post=4942"}],"version-history":[{"count":0,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts\/4942\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/media?parent=4942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/categories?post=4942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/tags?post=4942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}