{"id":6687,"date":"2019-05-10T12:14:12","date_gmt":"2019-05-10T11:14:12","guid":{"rendered":"https:\/\/www.legalprofession.de\/?p=6687"},"modified":"2023-07-04T18:17:39","modified_gmt":"2023-07-04T16:17:39","slug":"rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin","status":"publish","type":"post","link":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin","title":{"rendered":"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin"},"content":{"rendered":"<p>Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin &#8211; ein n\u00fcchterner Vergleich.<\/p>\n<p>Der Gesamtvorstand der RAK Berlin hat am 10.05.2019 beschlossen, die Verg\u00fctungsempfehlungen f\u00fcr die Auszubildenden in den Berufen Rechtsanwaltsfachangestellte und Rechtsanwalts- und Notarfachangestellte nach nur 16 Monaten erneut anzuheben. Ver\u00f6ffentlicht im digitalen <a href=\"http:\/\/kammerton.rak-berlin.de\/ausgabe\/04-2019\/Fachkraftenachwuchs-Quo-vadis\">Kammerton Ausgabe 04\/19<\/a>. Die Empfehlung ist verbindlich und darf bei neu abgeschossenen Ausbildungsverh\u00e4ltnissen nicht unterschritten werden. Die eigentliche Empfehlung f\u00fcr die Berliner Anwaltschaft liegt allerdings darin, noch ein bisschen was on top zu packen, denn selbst die\u00a0 Berliner Justiz zahlt mehr. Eine Besonderheit dieser Branche, dass man im \u00d6ffentlichen Dienst mehr verdient als in der freien Wirtschaft. Das w\u00e4re zum Beispiel im Gesundheitswesen undenkbar.<\/p>\n<p>Aber auch der Rechtsmarkt gestaltet sich anders, als es sich auf den ersten Blick darstellt. Wechselt die ReFa n\u00e4mlich nach ihrer Ausbildung in einer kleinen Kanzlei zu anderen Marktakteuren, zum Beispiel in eine internationalen Wirtschaftskanzlei, in eine WP-Gesellschaft oder eine Rechtsabteilung, erzielt eine Rechtsanwaltsfachangestellte durchaus ein Gehalt, das dieses S\u00e4ulendiagramm sprengen w\u00fcrde. Es sagt nur keiner. Ja, es ist bedauerlich, dass immer noch die kleinen Marktakteure ausbilden und die Gro\u00dfen mit attraktiver Verg\u00fctung nach erfolgreichem Abschluss werben. Aber das Verschweigen der Chancen und M\u00f6glichkeiten dieser Berufsgruppe schadet diesem langsam sterbenden Berufsbild und nutzt keinem.<\/p>\n<p>Ein erfolgsversprechender Weg bei der Nachwuchswerbung f\u00fcr die Rechtsanwaltsfachangestellten w\u00e4re es, stets die ganze Wahrheit zu sagen. Dazu z\u00e4hlt auch, dass man als einer der wenigen Bewerber f\u00fcr diesen Ausbildungsberuf bereits bei der Ausbildungsverg\u00fctung einen Verhandlungsspielraum hat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin &#8211; ein n\u00fcchterner Vergleich. Der Gesamtvorstand der RAK Berlin hat am 10.05.2019 beschlossen, die Verg\u00fctungsempfehlungen f\u00fcr die Auszubildenden in den Berufen Rechtsanwaltsfachangestellte und Rechtsanwalts- und Notarfachangestellte nach nur 16 Monaten erneut anzuheben. Ver\u00f6ffentlicht im digitalen Kammerton Ausgabe 04\/19. Die Empfehlung ist verbindlich und darf bei neu abgeschossenen Ausbildungsverh\u00e4ltnissen nicht unterschritten werden.&hellip; <a href=\"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin\">Continue reading&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":6688,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[548],"tags":[280,651,604],"class_list":["post-6687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reno-rechtsanwalts-und-notarfachangestellte","tag-gehalt","tag-justiz","tag-rak-berlin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin - LegalProfession\u00ae<\/title>\n<meta name=\"description\" content=\"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin. Die RAK Berlin hat 2019 beschlossen, die Verg\u00fctungsempfehlungen anzuheben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin - LegalProfession\u00ae\" \/>\n<meta property=\"og:description\" content=\"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin. Die RAK Berlin hat 2019 beschlossen, die Verg\u00fctungsempfehlungen anzuheben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin\" \/>\n<meta property=\"og:site_name\" content=\"LegalProfession\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-10T11:14:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T16:17:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.legalprofession.de\/wp-content\/uploads\/Verg\u00fctung-2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"993\" \/>\n\t<meta property=\"og:image:height\" content=\"645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marion Proft\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marion Proft\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin\"},\"author\":{\"name\":\"Marion Proft\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/person\\\/1e8822e456f8b1f7b7a81e32b14f81cf\"},\"headline\":\"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin\",\"datePublished\":\"2019-05-10T11:14:12+00:00\",\"dateModified\":\"2023-07-04T16:17:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin\"},\"wordCount\":253,\"publisher\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Verg%C3%BCtung-2019.jpg?fit=993%2C645&ssl=1\",\"keywords\":[\"Gehalt\",\"Justiz\",\"RAK Berlin\"],\"articleSection\":[\"ReNo Rechtsanwalts- und Notarfachangestellte\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin\",\"name\":\"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin - LegalProfession\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Verg%C3%BCtung-2019.jpg?fit=993%2C645&ssl=1\",\"datePublished\":\"2019-05-10T11:14:12+00:00\",\"dateModified\":\"2023-07-04T16:17:39+00:00\",\"description\":\"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin. Die RAK Berlin hat 2019 beschlossen, die Verg\u00fctungsempfehlungen anzuheben.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Verg%C3%BCtung-2019.jpg?fit=993%2C645&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Verg%C3%BCtung-2019.jpg?fit=993%2C645&ssl=1\",\"width\":993,\"height\":645,\"caption\":\"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.legalprofession.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#website\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/\",\"name\":\"LegalProfession\u00ae\",\"description\":\"Recruiting Coaching Consulting AZAV\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.legalprofession.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\",\"name\":\"LegalProfession\u00ae Recruitment Coaching Consulting\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Logo-LP-1.jpg?fit=354%2C141&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Logo-LP-1.jpg?fit=354%2C141&ssl=1\",\"width\":354,\"height\":141,\"caption\":\"LegalProfession\u00ae Recruitment Coaching Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/marion-proft-legalprofession\\\/\",\"https:\\\/\\\/www.xing.com\\\/profile\\\/Marion_Proft\\\/portfolio\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/person\\\/1e8822e456f8b1f7b7a81e32b14f81cf\",\"name\":\"Marion Proft\",\"description\":\"Marion Proft Recruitment, Coaching &amp; Berufsorientierung - AZAV Arbeitsvermittlung &amp; Job Coaching. Pers\u00f6nlich-professionell-perspektivisch. Zuversicht &amp; Future Fitness in unsicheren Zeiten.\",\"sameAs\":[\"https:\\\/\\\/www.legalprofession.de\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/marion-proft-legalprofession\\\/\"],\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/author\\\/admin-mpr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin - LegalProfession\u00ae","description":"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin. Die RAK Berlin hat 2019 beschlossen, die Verg\u00fctungsempfehlungen anzuheben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin","og_locale":"de_DE","og_type":"article","og_title":"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin - LegalProfession\u00ae","og_description":"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin. Die RAK Berlin hat 2019 beschlossen, die Verg\u00fctungsempfehlungen anzuheben.","og_url":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin","og_site_name":"LegalProfession\u00ae","article_published_time":"2019-05-10T11:14:12+00:00","article_modified_time":"2023-07-04T16:17:39+00:00","og_image":[{"width":993,"height":645,"url":"https:\/\/www.legalprofession.de\/wp-content\/uploads\/Verg\u00fctung-2019.jpg","type":"image\/jpeg"}],"author":"Marion Proft","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Marion Proft","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#article","isPartOf":{"@id":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin"},"author":{"name":"Marion Proft","@id":"https:\/\/www.legalprofession.de\/#\/schema\/person\/1e8822e456f8b1f7b7a81e32b14f81cf"},"headline":"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin","datePublished":"2019-05-10T11:14:12+00:00","dateModified":"2023-07-04T16:17:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin"},"wordCount":253,"publisher":{"@id":"https:\/\/www.legalprofession.de\/#organization"},"image":{"@id":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Verg%C3%BCtung-2019.jpg?fit=993%2C645&ssl=1","keywords":["Gehalt","Justiz","RAK Berlin"],"articleSection":["ReNo Rechtsanwalts- und Notarfachangestellte"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin","url":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin","name":"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin - LegalProfession\u00ae","isPartOf":{"@id":"https:\/\/www.legalprofession.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#primaryimage"},"image":{"@id":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Verg%C3%BCtung-2019.jpg?fit=993%2C645&ssl=1","datePublished":"2019-05-10T11:14:12+00:00","dateModified":"2023-07-04T16:17:39+00:00","description":"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin. Die RAK Berlin hat 2019 beschlossen, die Verg\u00fctungsempfehlungen anzuheben.","breadcrumb":{"@id":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#primaryimage","url":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Verg%C3%BCtung-2019.jpg?fit=993%2C645&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Verg%C3%BCtung-2019.jpg?fit=993%2C645&ssl=1","width":993,"height":645,"caption":"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalprofession.de\/index.php\/rechtsanwaltsfachangestellte-vs-justizfachangestellte-berlin#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.legalprofession.de\/"},{"@type":"ListItem","position":2,"name":"Rechtsanwaltsfachangestellte vs. Justizfachangestellte Berlin"}]},{"@type":"WebSite","@id":"https:\/\/www.legalprofession.de\/#website","url":"https:\/\/www.legalprofession.de\/","name":"LegalProfession\u00ae","description":"Recruiting Coaching Consulting AZAV","publisher":{"@id":"https:\/\/www.legalprofession.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalprofession.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.legalprofession.de\/#organization","name":"LegalProfession\u00ae Recruitment Coaching Consulting","url":"https:\/\/www.legalprofession.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalprofession.de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Logo-LP-1.jpg?fit=354%2C141&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Logo-LP-1.jpg?fit=354%2C141&ssl=1","width":354,"height":141,"caption":"LegalProfession\u00ae Recruitment Coaching Consulting"},"image":{"@id":"https:\/\/www.legalprofession.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/in\/marion-proft-legalprofession\/","https:\/\/www.xing.com\/profile\/Marion_Proft\/portfolio"]},{"@type":"Person","@id":"https:\/\/www.legalprofession.de\/#\/schema\/person\/1e8822e456f8b1f7b7a81e32b14f81cf","name":"Marion Proft","description":"Marion Proft Recruitment, Coaching &amp; Berufsorientierung - AZAV Arbeitsvermittlung &amp; Job Coaching. Pers\u00f6nlich-professionell-perspektivisch. Zuversicht &amp; Future Fitness in unsicheren Zeiten.","sameAs":["https:\/\/www.legalprofession.de","https:\/\/www.linkedin.com\/in\/marion-proft-legalprofession\/"],"url":"https:\/\/www.legalprofession.de\/index.php\/author\/admin-mpr"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Verg%C3%BCtung-2019.jpg?fit=993%2C645&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8oDIe-1JR","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts\/6687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/comments?post=6687"}],"version-history":[{"count":0,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts\/6687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/media\/6688"}],"wp:attachment":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/media?parent=6687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/categories?post=6687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/tags?post=6687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}