{"id":8301,"date":"2021-10-01T16:24:50","date_gmt":"2021-10-01T14:24:50","guid":{"rendered":"https:\/\/www.legalprofession.de\/?p=8301"},"modified":"2023-02-26T11:53:14","modified_gmt":"2023-02-26T10:53:14","slug":"reno-absolventen-2020-berlin","status":"publish","type":"post","link":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin","title":{"rendered":"ReNo-Absolventen 2020 Berlin"},"content":{"rendered":"<p>Pandemiebedingt erscheinen die Zahlen der ReNo-Absolventen 2020 Berlin etwas versp\u00e4tet. Was die <a href=\"https:\/\/www.rak-berlin.de\/\">Rechtsanwaltskammer Berlin<\/a> in ihrem Jahresbericht 2020 als &#8222;stabil trotz schwieriger Rahmenbedingungen&#8220; beschreibt, ist zwar keine positive Entwicklung, aber tats\u00e4chlich verh\u00e4ltnism\u00e4\u00dfig stabil. &#8222;Nur&#8220; 100 Auszubildende haben ihren Ausbildungsvertrag vorzeitig aufgel\u00f6st. Noch weniger abgeschlossene Ausbildungsvertr\u00e4ge als 2019 und 27% bestehen die Kammerpr\u00fcfung nicht. Es h\u00e4tte keiner Pandemie bedurft, um den ReNo-Beruf auf das Sterbebett zu legen. Seit Jahren siechen die Zahlen dahin. Berlin steht hier nur exemplarisch f\u00fcr die Gesamtsituation in Deutschland.<\/p>\n<h5><span style=\"color: #ff0000;\">Keine Werbung &#8211; schlechtes Image<\/span><\/h5>\n<p>Dass Ausbildungsmessen und Schulwerbeveranstaltungen pandemiebedingt nicht stattfinden konnten, ist keine Begr\u00fcndung daf\u00fcr, dass die Branche von der Jugend nicht wahrgenommen wird. Der Beruf ist nicht nur kaum bekannt, sondern hat auch ein schlechtes Image. Wer sich f\u00fcr eine Ausbildung zur ReNo entscheidet, kommt selten voller Begeisterung. Die Bewerber kommen meist auf Empfehlung der Agentur f\u00fcr Arbeit mit dem Hinweis, Anw\u00e4lte suchen immer, da bekommt jeder einen Job.<\/p>\n<h5><span style=\"color: #ff0000;\">Sinkende Qualit\u00e4t der Ausbildung<\/span><\/h5>\n<p>Da kann man nicht hoffen, dass die wenigen Auszubildenden einen guten Ausbildungsabschluss erzielen. Auch die Leistung ist entt\u00e4uschend. 20 % der Auszubildenden haben die Pr\u00fcfung nicht bestanden 30% haben nur ausreichend erzielt. Das ist alles andere als ausreichend f\u00fcr Berlin.<\/p>\n<h5><span style=\"color: #ff0000;\">Der Beruf ist besser als sein Ruf<\/span><\/h5>\n<p>Dabei hat der Beruf sehr an Attraktivit\u00e4t gewonnen. Krisensicher und unverzichtbar &#8211; das hat die Pandemie gezeigt. Sogar eine Flexibilisierung der Arbeitszeit ist m\u00f6glich. Homeoffice, Selbstorganisation und Vertrauensarbeitszeit &#8211; wer hatte sich das vor wenigen Jahren tr\u00e4umen lassen? Es muss sich nur noch rumsprechen&#8230;<\/p>\n<p>Antworten und Informationen zu unseren Angeboten finden Sie hier: <a href=\"https:\/\/www.legalprofession.de\/index.php\/consulting\/ausbildungsmarketing\">Ausbildungsmarketing<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pandemiebedingt erscheinen die Zahlen der ReNo-Absolventen 2020 Berlin etwas versp\u00e4tet. Was die Rechtsanwaltskammer Berlin in ihrem Jahresbericht 2020 als &#8222;stabil trotz schwieriger Rahmenbedingungen&#8220; beschreibt, ist zwar keine positive Entwicklung, aber tats\u00e4chlich verh\u00e4ltnism\u00e4\u00dfig stabil. &#8222;Nur&#8220; 100 Auszubildende haben ihren Ausbildungsvertrag vorzeitig aufgel\u00f6st. Noch weniger abgeschlossene Ausbildungsvertr\u00e4ge als 2019 und 27% bestehen die Kammerpr\u00fcfung nicht. Es h\u00e4tte&hellip; <a href=\"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin\">Continue reading&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":8313,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[266,548],"tags":[604,300],"class_list":["post-8301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausbildungsmarketing","category-reno-rechtsanwalts-und-notarfachangestellte","tag-rak-berlin","tag-statistik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ReNo-Absolventen 2020 Berlin - LegalProfession\u00ae<\/title>\n<meta name=\"description\" content=\"ReNo-Absolventen 2020 Berlin. Einhundert Auszubildende haben ihren Ausbildungsvertrag vorzeitig aufgel\u00f6st.\u00a0Sinkende Qualit\u00e4t der Ausbildung\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ReNo-Absolventen 2020 Berlin - LegalProfession\u00ae\" \/>\n<meta property=\"og:description\" content=\"ReNo-Absolventen 2020 Berlin. Einhundert Auszubildende haben ihren Ausbildungsvertrag vorzeitig aufgel\u00f6st.\u00a0Sinkende Qualit\u00e4t der Ausbildung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin\" \/>\n<meta property=\"og:site_name\" content=\"LegalProfession\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-01T14:24:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-26T10:53:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.legalprofession.de\/wp-content\/uploads\/ReNo-Absolventen-2020.png\" \/>\n\t<meta property=\"og:image:width\" content=\"916\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marion Proft\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marion Proft\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin\"},\"author\":{\"name\":\"Marion Proft\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/person\\\/1e8822e456f8b1f7b7a81e32b14f81cf\"},\"headline\":\"ReNo-Absolventen 2020 Berlin\",\"datePublished\":\"2021-10-01T14:24:50+00:00\",\"dateModified\":\"2023-02-26T10:53:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin\"},\"wordCount\":274,\"publisher\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/ReNo-Absolventen-2020.png?fit=916%2C472&ssl=1\",\"keywords\":[\"RAK Berlin\",\"Statistik\"],\"articleSection\":[\"Ausbildungsmarketing\",\"ReNo Rechtsanwalts- und Notarfachangestellte\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin\",\"name\":\"ReNo-Absolventen 2020 Berlin - LegalProfession\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/ReNo-Absolventen-2020.png?fit=916%2C472&ssl=1\",\"datePublished\":\"2021-10-01T14:24:50+00:00\",\"dateModified\":\"2023-02-26T10:53:14+00:00\",\"description\":\"ReNo-Absolventen 2020 Berlin. Einhundert Auszubildende haben ihren Ausbildungsvertrag vorzeitig aufgel\u00f6st.\u00a0Sinkende Qualit\u00e4t der Ausbildung\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/ReNo-Absolventen-2020.png?fit=916%2C472&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/ReNo-Absolventen-2020.png?fit=916%2C472&ssl=1\",\"width\":916,\"height\":472,\"caption\":\"ReNo Absolventen 2020 Berlin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/reno-absolventen-2020-berlin#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.legalprofession.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ReNo-Absolventen 2020 Berlin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#website\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/\",\"name\":\"LegalProfession\u00ae\",\"description\":\"Recruiting Coaching Consulting AZAV\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.legalprofession.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#organization\",\"name\":\"LegalProfession\u00ae Recruitment Coaching Consulting\",\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Logo-LP-1.jpg?fit=354%2C141&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.legalprofession.de\\\/wp-content\\\/uploads\\\/Logo-LP-1.jpg?fit=354%2C141&ssl=1\",\"width\":354,\"height\":141,\"caption\":\"LegalProfession\u00ae Recruitment Coaching Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/marion-proft-legalprofession\\\/\",\"https:\\\/\\\/www.xing.com\\\/profile\\\/Marion_Proft\\\/portfolio\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.legalprofession.de\\\/#\\\/schema\\\/person\\\/1e8822e456f8b1f7b7a81e32b14f81cf\",\"name\":\"Marion Proft\",\"description\":\"Marion Proft Recruitment, Coaching &amp; Berufsorientierung - AZAV Arbeitsvermittlung &amp; Job Coaching. Pers\u00f6nlich-professionell-perspektivisch. Zuversicht &amp; Future Fitness in unsicheren Zeiten.\",\"sameAs\":[\"https:\\\/\\\/www.legalprofession.de\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/marion-proft-legalprofession\\\/\"],\"url\":\"https:\\\/\\\/www.legalprofession.de\\\/index.php\\\/author\\\/admin-mpr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ReNo-Absolventen 2020 Berlin - LegalProfession\u00ae","description":"ReNo-Absolventen 2020 Berlin. Einhundert Auszubildende haben ihren Ausbildungsvertrag vorzeitig aufgel\u00f6st.\u00a0Sinkende Qualit\u00e4t der Ausbildung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin","og_locale":"de_DE","og_type":"article","og_title":"ReNo-Absolventen 2020 Berlin - LegalProfession\u00ae","og_description":"ReNo-Absolventen 2020 Berlin. Einhundert Auszubildende haben ihren Ausbildungsvertrag vorzeitig aufgel\u00f6st.\u00a0Sinkende Qualit\u00e4t der Ausbildung","og_url":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin","og_site_name":"LegalProfession\u00ae","article_published_time":"2021-10-01T14:24:50+00:00","article_modified_time":"2023-02-26T10:53:14+00:00","og_image":[{"width":916,"height":472,"url":"https:\/\/www.legalprofession.de\/wp-content\/uploads\/ReNo-Absolventen-2020.png","type":"image\/png"}],"author":"Marion Proft","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Marion Proft","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin#article","isPartOf":{"@id":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin"},"author":{"name":"Marion Proft","@id":"https:\/\/www.legalprofession.de\/#\/schema\/person\/1e8822e456f8b1f7b7a81e32b14f81cf"},"headline":"ReNo-Absolventen 2020 Berlin","datePublished":"2021-10-01T14:24:50+00:00","dateModified":"2023-02-26T10:53:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin"},"wordCount":274,"publisher":{"@id":"https:\/\/www.legalprofession.de\/#organization"},"image":{"@id":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/ReNo-Absolventen-2020.png?fit=916%2C472&ssl=1","keywords":["RAK Berlin","Statistik"],"articleSection":["Ausbildungsmarketing","ReNo Rechtsanwalts- und Notarfachangestellte"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin","url":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin","name":"ReNo-Absolventen 2020 Berlin - LegalProfession\u00ae","isPartOf":{"@id":"https:\/\/www.legalprofession.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin#primaryimage"},"image":{"@id":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/ReNo-Absolventen-2020.png?fit=916%2C472&ssl=1","datePublished":"2021-10-01T14:24:50+00:00","dateModified":"2023-02-26T10:53:14+00:00","description":"ReNo-Absolventen 2020 Berlin. Einhundert Auszubildende haben ihren Ausbildungsvertrag vorzeitig aufgel\u00f6st.\u00a0Sinkende Qualit\u00e4t der Ausbildung","breadcrumb":{"@id":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin#primaryimage","url":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/ReNo-Absolventen-2020.png?fit=916%2C472&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/ReNo-Absolventen-2020.png?fit=916%2C472&ssl=1","width":916,"height":472,"caption":"ReNo Absolventen 2020 Berlin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalprofession.de\/index.php\/reno-absolventen-2020-berlin#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.legalprofession.de\/"},{"@type":"ListItem","position":2,"name":"ReNo-Absolventen 2020 Berlin"}]},{"@type":"WebSite","@id":"https:\/\/www.legalprofession.de\/#website","url":"https:\/\/www.legalprofession.de\/","name":"LegalProfession\u00ae","description":"Recruiting Coaching Consulting AZAV","publisher":{"@id":"https:\/\/www.legalprofession.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalprofession.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.legalprofession.de\/#organization","name":"LegalProfession\u00ae Recruitment Coaching Consulting","url":"https:\/\/www.legalprofession.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalprofession.de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Logo-LP-1.jpg?fit=354%2C141&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/Logo-LP-1.jpg?fit=354%2C141&ssl=1","width":354,"height":141,"caption":"LegalProfession\u00ae Recruitment Coaching Consulting"},"image":{"@id":"https:\/\/www.legalprofession.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/in\/marion-proft-legalprofession\/","https:\/\/www.xing.com\/profile\/Marion_Proft\/portfolio"]},{"@type":"Person","@id":"https:\/\/www.legalprofession.de\/#\/schema\/person\/1e8822e456f8b1f7b7a81e32b14f81cf","name":"Marion Proft","description":"Marion Proft Recruitment, Coaching &amp; Berufsorientierung - AZAV Arbeitsvermittlung &amp; Job Coaching. Pers\u00f6nlich-professionell-perspektivisch. Zuversicht &amp; Future Fitness in unsicheren Zeiten.","sameAs":["https:\/\/www.legalprofession.de","https:\/\/www.linkedin.com\/in\/marion-proft-legalprofession\/"],"url":"https:\/\/www.legalprofession.de\/index.php\/author\/admin-mpr"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.legalprofession.de\/wp-content\/uploads\/ReNo-Absolventen-2020.png?fit=916%2C472&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8oDIe-29T","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts\/8301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/comments?post=8301"}],"version-history":[{"count":0,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/posts\/8301\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/media\/8313"}],"wp:attachment":[{"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/media?parent=8301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/categories?post=8301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalprofession.de\/index.php\/wp-json\/wp\/v2\/tags?post=8301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}